{"id":9,"date":"2025-11-06T17:44:39","date_gmt":"2025-11-06T16:44:39","guid":{"rendered":"https:\/\/rutasmototours.com\/?page_id=9"},"modified":"2025-12-04T19:07:18","modified_gmt":"2025-12-04T18:07:18","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/rutasmototours.com\/fr\/politica-de-privacidad\/","title":{"rendered":"politique de confidentialit\u00e9"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(0,0,0,0.8) 0%|rgba(0,0,0,0.4) 30%\u00bb background_image=\u00bbhttps:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/IMG_20240524_091310-copia.webp\u00bb background_position=\u00bbbottom_center\u00bb background_vertical_offset=\u00bb15%\u00bb background_blend=\u00bboverlay\u00bb height=\u00bb40vh\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb positioning=\u00bbabsolute\u00bb position_origin_a=\u00bbbottom_center\u00bb width=\u00bb90%\u00bb max_width=\u00bb1000px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb|800|||||||\u00bb header_font_size=\u00bb50px\u00bb background_layout=\u00bbdark\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Pol\u00edtica de Privacidad<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb max_width=\u00bb1000px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>El presente aviso legal (en adelante, el \u00abAviso Legal\u00bb) regula el uso del servicio del portal de Internet https:\/\/rutasmototours.com\/ (en adelante, el \u00abWeb\u00bb) de RUTAS MOTO TOURS S.L. con domicilio social en CALLE MIRADOR DE LOBRES, 18610 LOBRES \u2013 SALOBRE\u00d1A, ESPA\u00d1A con CIF B22758999<\/p>\n<p><strong>Legislaci\u00f3n<\/strong><\/p>\n<p>Con car\u00e1cter general las relaciones entre RUTAS MOTO TOURS S.L. con los Usuarios de sus servicios telem\u00e1ticos, presentes en la web, se encuentran sometidas a la legislaci\u00f3n y jurisdicci\u00f3n espa\u00f1olas.<\/p>\n<p>Las partes renuncian expresamente al fuero que les pudiera corresponder y someten expresamente a los Juzgados y Tribunales de GRANADA para resolver cualquier controversia que pueda surgir en la interpretaci\u00f3n o ejecuci\u00f3n de las presentes condiciones contractuales.<\/p>\n<p><strong>Contenido y uso<\/strong><\/p>\n<p>El Usuario queda informado, y acepta, que el acceso a la presente web no supone, en modo alguno, el inicio de una relaci\u00f3n comercial con RUTAS MOTO TOURS S.L..<\/p>\n<p>El titular del web no se identifica con las opiniones vertidas en el mismo por sus colaboradores. La Empresa se reserva el derecho de efectuar sin previo aviso las modificaciones que considere oportunas en su Web, pudiendo cambiar, suprimir o a\u00f1adir tanto los contenidos y servicios que se presten a trav\u00e9s de la misma como la forma en la que \u00e9stos aparezcan presentados o localizados en sus servidores.<\/p>\n<p><strong>Propiedad intelectual e industrial<\/strong><\/p>\n<p>Los derechos de propiedad intelectual del contenido de las p\u00e1ginas web, su dise\u00f1o gr\u00e1fico y c\u00f3digos son titularidad de RUTAS MOTO TOURS S.L. y, por tanto, queda prohibida su reproducci\u00f3n, distribuci\u00f3n, comunicaci\u00f3n p\u00fablica, transformaci\u00f3n o cualquier otra actividad que se pueda realizar con los contenidos de sus p\u00e1ginas web ni aun citando las fuentes, salvo consentimiento por escrito de RUTAS MOTO TOURS S.L.. Todos los nombres comerciales, marcas o signos distintos de cualquier clase contenidos en las p\u00e1ginas web de la Empresa son propiedad de sus due\u00f1os y est\u00e1n protegidos por ley.<\/p>\n<p><strong>Enlaces (Links)<\/strong><\/p>\n<p>La presencia de enlaces (links) en las p\u00e1ginas web de RUTAS MOTO TOURS S.L. tiene finalidad meramente informativa y en ning\u00fan caso supone sugerencia, invitaci\u00f3n o recomendaci\u00f3n sobre los mismos.<\/p>\n<p><strong>Confidencialidad y Protecci\u00f3n de Datos<\/strong><\/p>\n<p>A efecto de lo previsto en RGPD de 27 de abril de 2016, RUTAS MOTO TOURS S.L. informa al Usuario de la existencia de un tratamiento automatizado de datos de car\u00e1cter personal creado por y para RUTAS MOTO TOURS S.L. y bajo su responsabilidad, con la finalidad de realizar el mantenimiento y gesti\u00f3n de la relaci\u00f3n con el Usuario, as\u00ed como las labores de informaci\u00f3n. En el momento de la aceptaci\u00f3n de las presentes condiciones generales, RUTAS MOTO TOURS S.L. precisar\u00e1 del Usuario la recogida de unos datos imprescindibles para la prestaci\u00f3n de sus servicios.<\/p>\n<p><strong>Registro de ficheros y formularios<\/strong><\/p>\n<p>La cumplimentaci\u00f3n del formulario de registro es obligatoria para acceder y disfrutar de determinados servicios ofrecidos en la web. El no facilitar los datos personales solicitados o el no aceptar la presente pol\u00edtica de protecci\u00f3n de datos supone la imposibilidad de suscribirse, registrarse o participar en cualquiera de las promociones en las que se soliciten datos car\u00e1cter personal.<\/p>\n<p>A efecto de lo previsto en RGPD de 27 de abril de 2016, le informamos que los datos personales que se obtengan como consecuencia de su registro como Usuario, ser\u00e1n incorporados a un fichero titularidad de RUTAS MOTO TOURS S.L. con domicilio social en en CALLE MIRADOR DE LOBRES, 18610 LOBRES \u2013 SALOBRE\u00d1A, ESPA\u00d1A con CIF B22758999<br \/>, teniendo implementadas las medidas de seguridad establecidas en el Real Decreto 1720\/2007, de 11 de junio.<\/p>\n<p><strong>Exactitud y veracidad de los datos facilitados<\/strong><\/p>\n<p>El Usuario es el \u00fanico responsable de la veracidad y correcci\u00f3n de los datos incluidos, exoner\u00e1ndose RUTAS MOTO TOURS S.L. de cualquier responsabilidad al respecto. Los usuarios garantizan y responden, en cualquier caso, de la exactitud, vigencia y autenticidad de los datos personales facilitados, y se comprometen a mantenerlos debidamente actualizados. El usuario acepta proporcionar informaci\u00f3n completa y correcta en el formulario de registro o suscripci\u00f3n. RUTAS MOTO TOURS S.L. no responde de la veracidad de las informaciones que no sean de elaboraci\u00f3n propia y de las que se indique otra fuente, por lo que tampoco asume responsabilidad alguna en cuanto a hipot\u00e9ticos perjuicios que pudieran originarse por el uso de dicha informaci\u00f3n.\u00a0 RUTAS MOTO TOURS S.L. se reserva el derecho a actualizar, modificar o eliminar la informaci\u00f3n contenida en sus p\u00e1ginas web pudiendo incluso limitar o no permitir el acceso a dicha informaci\u00f3n. Se exonera a RUTAS MOTO TOURS S.L. de responsabilidad ante cualquier da\u00f1o o perjuicio que pudiera sufrir el Usuario como consecuencia de errores, defectos u omisiones, en la informaci\u00f3n facilitada por RUTAS MOTO TOURS S.L. siempre que proceda de fuentes ajenas a RUTAS MOTO TOURS S.L..<\/p>\n<p><strong>Cookies<\/strong><\/p>\n<p>El sitio https:\/\/rutasmototours.com\/ no utiliza cookies, considerando tales ficheros f\u00edsicos de informaci\u00f3n alojados en el propio terminal del usuario y sirven para facilitar la navegaci\u00f3n del usuario por el portal. De todas formas, el usuario tiene la posibilidad de configurar el navegador de tal modo que impida la instalaci\u00f3n de estos archivos.<\/p>\n<p><strong>Finalidades<\/strong><\/p>\n<p>Las finalidades de RUTAS MOTO TOURS S.L. son el mantenimiento y gesti\u00f3n de la relaci\u00f3n con el Usuario, as\u00ed como las labores de informaci\u00f3n.<\/p>\n<p><strong>Menores de edad<\/strong><\/p>\n<p>En el supuesto que algunos de nuestros servicios vayan dirigidos espec\u00edficamente a menores de edad, RUTAS MOTO TOURS S.L. solicitar\u00e1 la conformidad de los padres o tutores para la recogida de los datos personales o, en su caso, para el tratamiento automatizado de los datos.<\/p>\n<p><strong>Cesi\u00f3n de datos a terceros<\/strong><\/p>\n<p>RUTAS MOTO TOURS S.L. no realizar\u00e1 cesi\u00f3n de datos de los usuarios a terceros.<\/p>\n<p><strong>Ejercicio de derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n y oposici\u00f3n<\/strong><\/p>\n<p>Podr\u00e1 dirigir sus comunicaciones y ejercitar los derechos de acceso, rectificaci\u00f3n, supresi\u00f3n, limitaci\u00f3n, portabilidad y oposici\u00f3n en la direcci\u00f3n de Internet a https:\/\/rutasmototours.com\/ o bien por correo ordinario dirigido a RUTAS MOTO TOURS S.L., <strong>Ref. RGPD<\/strong>, en CALLE MIRADOR DE LOBRES, 18610 LOBRES \u2013 SALOBRE\u00d1A, ESPA\u00d1A. Para ejercer dichos derechos es necesario que usted acredite su personalidad frente a RUTAS MOTO TOURS S.L. mediante el env\u00edo de fotocopia de Documento Nacional de Identidad o cualquier otro medio v\u00e1lido en Derecho. No obstante, la modificaci\u00f3n o rectificaci\u00f3n de sus datos de registro se podr\u00e1 realizar en el propio Site identific\u00e1ndose, previamente, con su usuario y contrase\u00f1a.<\/p>\n<p><strong>Medidas de seguridad<\/strong><\/p>\n<p>RUTAS MOTO TOURS S.L. ha adoptado los niveles de seguridad de protecci\u00f3n de los Datos Personales legalmente requeridos, y procuran instalar aquellos otros medios y medidas t\u00e9cnicas adicionales a su alcance para evitar la p\u00e9rdida, mal uso, alteraci\u00f3n, acceso no autorizado y robo de los Datos Personales facilitados a RUTAS MOTO TOURS S.L. no ser\u00e1 responsable de posibles da\u00f1os o perjuicios que se pudieran derivar de interferencias, omisiones, interrupciones, virus inform\u00e1ticos, aver\u00edas telef\u00f3nicas o desconexiones en el funcionamiento operativo de este sistema electr\u00f3nico, motivadas por causas ajenas a RUTAS MOTO TOURS S.L.; de retrasos o bloqueos en el uso del presente sistema electr\u00f3nico causados por deficiencias o sobrecargas de l\u00edneas telef\u00f3nicas o sobrecargas en el Centro de Procesos de Datos, en el sistema de Internet o en otros sistemas electr\u00f3nicos, as\u00ed como de da\u00f1os que puedan ser causados por terceras personas mediante intromisiones ileg\u00edtimas fuera del control de RUTAS MOTO TOURS S.L.. Ello, no obstante, el Usuario debe ser consciente de que las medidas de seguridad en Internet no son inexpugnables.<\/p>\n<p><strong>Aceptaci\u00f3n y consentimiento<\/strong><\/p>\n<p>El usuario declara haber sido informado de las condiciones sobre protecci\u00f3n de datos personales, aceptando y consintiendo el tratamiento automatizado de los mismos por parte de RUTAS MOTO TOURS S.L., en la forma y para las finalidades indicadas en la presente Pol\u00edtica de Protecci\u00f3n de Datos Personales. Ciertos servicios prestados en el Portal pueden contener condiciones particulares con previsiones espec\u00edficas en materia de protecci\u00f3n de Datos Personales.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de PrivacidadEl presente aviso legal (en adelante, el \u00abAviso Legal\u00bb) regula el uso del servicio del portal de Internet https:\/\/rutasmototours.com\/ (en adelante, el \u00abWeb\u00bb) de RUTAS MOTO TOURS S.L. con domicilio social en CALLE MIRADOR DE LOBRES, 18610 LOBRES \u2013 SALOBRE\u00d1A, ESPA\u00d1A con CIF B22758999 Legislaci\u00f3n Con car\u00e1cter general las relaciones entre RUTAS MOTO [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":0,"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"wp:attachment":[{"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}