{"id":228,"date":"2025-11-10T12:15:15","date_gmt":"2025-11-10T11:15:15","guid":{"rendered":"https:\/\/rutasmototours.com\/?page_id=228"},"modified":"2026-08-21T09:44:38","modified_gmt":"2026-08-21T07:44:38","slug":"marruecos-medio-alto-atlas-y-desierto-en-9-dias","status":"publish","type":"page","link":"https:\/\/rutasmototours.com\/fr\/marruecos-medio-alto-atlas-y-desierto-en-9-dias\/","title":{"rendered":"Marruecos \u2013 Medio, Alto Atlas y Desierto en 9 d\u00edas"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(0,0,0,0.2)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(0,0,0,0.7) 0%|rgba(0,0,0,0.4) 20%\u00bb background_image=\u00bbhttps:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/pexels-sanat-anghan-25736600-10099969.webp\u00bb background_blend=\u00bboverlay\u00bb height=\u00bb90vh\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb positioning=\u00bbabsolute\u00bb position_origin_a=\u00bbcenter_center\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.2em\u00bb header_font=\u00bb|800|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb50px\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb text_font_size_tablet=\u00bb24px\u00bb text_font_size_phone=\u00bb20px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_text_align_tablet=\u00bb\u00bb header_text_align_phone=\u00bbcenter\u00bb header_text_align_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb60px\u00bb header_font_size_phone=\u00bb38px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bb\u00bb text_orientation_phone=\u00bbcenter\u00bb text_orientation_last_edited=\u00bbon|phone\u00bb header_text_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Medio, Alto Atlas y Desierto en 9 d\u00edas<\/h1>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb#apuntarme\u00bb button_text=\u00bbApuntarme\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb|600||on|||||\u00bb custom_padding=\u00bb15px|30px|15px|30px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_icon font_icon=\u00bb&#x3b;||divi||400&#8243; icon_color=\u00bb#FFFFFF\u00bb icon_width=\u00bb25px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbtop\u00bb animation_duration=\u00bb2000ms\u00bb animation_intensity_slide=\u00bb10%\u00bb animation_repeat=\u00bbloop\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#B94E40&#8243; custom_padding=\u00bb10px||10px||true|false\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||20px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700|||||||\u00bb text_font_size=\u00bb20px\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Enlaces R\u00e1pidos<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_6,1_6,1_6,1_6,1_6,1_6&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb95%\u00bb max_width=\u00bb1500px\u00bb custom_css_main_element=\u00bbdisplay: flex;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#DBA149&#8243; custom_padding=\u00bb15px|10px|15px|10px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb transform_scale__hover=\u00bb105%|105%\u00bb][et_pb_blurb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf05a;||fa||900&#8243; icon_color=\u00bb#FFFFFF\u00bb image_icon_width=\u00bb50px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bb|700||on|||||\u00bb body_font_size=\u00bb16px\u00bb background_enable_color=\u00bboff\u00bb image_icon_custom_margin=\u00bb||-10px||false|false\u00bb image_icon_custom_padding=\u00bb||||false|false\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb animation=\u00bboff\u00bb link_option_url=\u00bb#info\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Informaci\u00f3n<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#DBA149&#8243; custom_padding=\u00bb15px|10px|15px|10px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb105%|105%\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb][et_pb_blurb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf0ae;||fa||900&#8243; icon_color=\u00bb#FFFFFF\u00bb image_icon_width=\u00bb50px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bb|700||on|||||\u00bb body_font_size=\u00bb16px\u00bb background_enable_color=\u00bboff\u00bb image_icon_custom_margin=\u00bb||-10px||false|false\u00bb image_icon_custom_padding=\u00bb||||false|false\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb animation=\u00bboff\u00bb link_option_url=\u00bb#incluido\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u00bfQu\u00e9 incluye?<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#DBA149&#8243; custom_padding=\u00bb15px|10px|15px|10px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb105%|105%\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb][et_pb_blurb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf5a0;||fa||900&#8243; icon_color=\u00bb#FFFFFF\u00bb image_icon_width=\u00bb50px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bb|700||on|||||\u00bb body_font_size=\u00bb16px\u00bb background_enable_color=\u00bboff\u00bb image_icon_custom_margin=\u00bb||-10px||false|false\u00bb image_icon_custom_padding=\u00bb||||false|false\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb animation=\u00bboff\u00bb link_option_url=\u00bb#mapa\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Mapa de la ruta<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#DBA149&#8243; custom_padding=\u00bb15px|10px|15px|10px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb105%|105%\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb][et_pb_blurb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf21c;||fa||900&#8243; icon_color=\u00bb#FFFFFF\u00bb image_icon_width=\u00bb50px\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bb|700||on|||||\u00bb body_font_size=\u00bb16px\u00bb background_enable_color=\u00bboff\u00bb image_icon_custom_margin=\u00bb||-10px||false|false\u00bb image_icon_custom_padding=\u00bb||||false|false\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb animation=\u00bboff\u00bb link_option_url=\u00bb#enlaces\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Alquiler y transport moto<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#DBA149&#8243; custom_padding=\u00bb15px|10px|15px|10px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb105%|105%\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb][et_pb_blurb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf4d7;||fa||900&#8243; icon_color=\u00bb#FFFFFF\u00bb image_icon_width=\u00bb50px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bb|700||on|||||\u00bb body_font_size=\u00bb16px\u00bb background_enable_color=\u00bboff\u00bb image_icon_custom_margin=\u00bb||-10px||false|false\u00bb image_icon_custom_padding=\u00bb||||false|false\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb animation=\u00bboff\u00bb link_option_url=\u00bb#itinerario\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Itinerario<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#DBA149&#8243; custom_padding=\u00bb15px|10px|15px|10px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb105%|105%\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb][et_pb_blurb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe075;||divi||400&#8243; icon_color=\u00bb#FFFFFF\u00bb image_icon_width=\u00bb50px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb body_font=\u00bb|700||on|||||\u00bb body_font_size=\u00bb16px\u00bb background_enable_color=\u00bboff\u00bb image_icon_custom_margin=\u00bb||-10px||false|false\u00bb image_icon_custom_padding=\u00bb||||false|false\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb animation=\u00bboff\u00bb link_option_url=\u00bb#galeria\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Galer\u00eda<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#F7F7F7&#8243; da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbmargin: auto;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||15px||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Descripci\u00f3n:<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||||false|false\u00bb hover_enabled=\u00bb0&#8243; header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]Descubrimiento de Marruecos en moto: Atlas, desierto y ciudades imperiales<\/p>\n<p>Este viaje en moto por Marruecos de 9 d\u00edas nos llevar\u00e1 desde las monta\u00f1as del Rif hasta las dunas del Sahara, atravesando el Medio y Alto Atlas, gargantas espectaculares, cascadas, lagos y ciudades cargadas de historia. Una ruta organizada en moto por Marruecos pensada para quienes quieren disfrutar tanto de la conducci\u00f3n como de la extraordinaria diversidad de paisajes y culturas del pa\u00eds.<\/p>\n<p>Tras desembarcar en Tanger Med, pondremos rumbo a Chefchaouen, la famosa \u00abCiudad Azul\u00bb, enclavada en el coraz\u00f3n de las monta\u00f1as del Rif. Sus callejuelas te\u00f1idas de azul, sus peque\u00f1as plazas y su ambiente tranquilo nos ofrecer\u00e1n una primera inmersi\u00f3n en Marruecos y el escenario perfecto para comenzar nuestra aventura sobre dos ruedas.<\/p>\n<p>Continuaremos nuestra ruta en moto por el Medio Atlas hasta llegar a Midelt, rodeada de monta\u00f1as y grandes espacios abiertos. Si las condiciones meteorol\u00f3gicas de los d\u00edas anteriores y del propio d\u00eda lo permiten, podremos acercarnos a las antiguas minas de Ahouli, antes de continuar hacia el sur. Poco a poco, el paisaje cambiar\u00e1 hasta conducirnos a las majestuosas dunas de Merzouga, donde el Erg Chebbi nos regalar\u00e1 uno de los grandes momentos del viaje.<\/p>\n<p>En Merzouga dedicaremos una jornada a descubrir y disfrutar de la magia del desierto de Marruecos, combinando excursiones, actividades, visitas y momentos de descanso. Aqu\u00ed dejaremos las motos durante unas horas para vivir el Sahara de otra manera, disfrutar de su inmensidad y descubrir la hospitalidad del sur marroqu\u00ed. Pasar una noche bajo las estrellas del desierto ser\u00e1, sin duda, uno de esos recuerdos que permanecer\u00e1n mucho despu\u00e9s del regreso.<br \/>\n[\/et_pb_text][et_pb_button button_url=\u00bb#apuntarme\u00bb button_text=\u00bbApuntarme\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb|600||on|||||\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb||30px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb15px|30px|15px|30px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbmargin: auto;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/07\/IMG_20260522_113229-scaled.jpg\u00bb title_text=\u00bbIMG_20260522_113229&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb2_5,3_5&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbmargin: auto;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/07\/1-47-scaled.jpg\u00bb title_text=\u00bb1 (47)\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb||30px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbmargin: auto;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||||false|false\u00bb hover_enabled=\u00bb0&#8243; header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]Al d\u00eda siguiente dejaremos atr\u00e1s Merzouga para iniciar una de las grandes etapas de este viaje organizado en moto por Marruecos. Alcanzaremos las espectaculares gargantas del Todra antes de continuar hacia Agoudal, un aut\u00e9ntico pueblo bereber enclavado en las monta\u00f1as. Seguiremos despu\u00e9s hacia las gargantas del Dad\u00e8s y los famosos Dedos de Mono, entre carreteras sinuosas y sorprendentes formaciones rocosas, antes de continuar hacia Ouarzazate y finalizar la jornada en la regi\u00f3n de Marrakech.<\/p>\n<p>A la ma\u00f1ana siguiente cambiaremos nuevamente de paisaje para dirigirnos hacia las famosas cascadas de Ouzoud, las m\u00e1s altas de Marruecos. Despu\u00e9s de disfrutar de este espectacular entorno natural, continuaremos hacia Bin El Ouidane, un magn\u00edfico lago rodeado de monta\u00f1as. Una etapa diferente, m\u00e1s tranquila y especialmente paisaj\u00edstica, que nos permitir\u00e1 descubrir otra cara del interior de Marruecos.<\/p>\n<p>Nuestra ruta en moto por Marruecos continuar\u00e1 hacia Mekn\u00e9s, una de las cuatro ciudades imperiales del pa\u00eds. Al final de la jornada tendremos tiempo libre para descubrirla a nuestro ritmo, pasear por su medina, contemplar sus monumentales puertas o simplemente disfrutar del ambiente de sus plazas hist\u00f3ricas.<\/p>\n<p>Finalmente pondremos rumbo a Tanger Med para embarcar en el ferry de regreso a Algeciras. Nueve d\u00edas despu\u00e9s, habremos recorrido algunos de los paisajes m\u00e1s impresionantes de Marruecos: las monta\u00f1as del Rif, el Medio y Alto Atlas, las dunas de Merzouga, las gargantas del Todra y del Dad\u00e8s, las cascadas de Ouzoud, Bin El Ouidane y una de sus grandes ciudades imperiales.<\/p>\n<p>Nueve d\u00edas de carreteras, monta\u00f1as, desierto, cultura y encuentros para descubrir Marruecos de la mejor manera que conocemos: sobre dos ruedas.<br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbmargin: auto;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||15px||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Los + del viaje:<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]\u2705 Visita de Chefachaouen[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u2705 Medio-Atlas<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u2705 Minas de Ahouli (Seg\u00fan las condiciones meteorol\u00f3gicas del d\u00eda y de los d\u00edas previos)<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]\u2705 Gargantas del Ziz[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]\u2705 Dunas de Erg Chebbi con actividades[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u2705 C\u00e1rcel Portugu\u00e9sa de Gara Medouar, Gargantas del Todra y del Dades<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u2705 Alta-Atlas y la subida del Tizi N\u2019Tichka (2260 metros de altitud)<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]\u2705  Cascadas de Ouzoud[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]\u2705 El lago de Bin El Ouidane [\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u2705 Parada en Meknes<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]\u2705 Los paisajes de monta\u00f1as y desierto impresionantes con geolog\u00eda incre\u00edble[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb background_color=\u00bb#F7F7F7&#8243; custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb10px|15px|10px|15px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u2705 La asistencia durante el viaje con dos gu\u00edas<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb#apuntarme\u00bb button_text=\u00bbApuntarme\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb|600||on|||||\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb||30px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb15px|30px|15px|30px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbmargin: auto;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25.jpg\u00bb alt=\u00bbruta en moto vuelta de andalucia en 9 dias\u00bb title_text=\u00bbMHAD9 \u2013 Medio, Alto Atlas y Desierto-25&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection\u00bb module_id=\u00bbinfo\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#F7F7F7&#8243; da_popup_slug=\u00bbinfo\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||10px||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbcenter\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>M\u00e1s informaci\u00f3n<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; use_custom_gutter=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbDuraci\u00f3n\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf017;||fa||400&#8243; icon_color=\u00bb#000000&#8243; image_icon_width=\u00bb50px\u00bb content_max_width=\u00bb100%\u00bb icon_placement_last_edited=\u00bboff|desktop\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb animation=\u00bboff\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb background__hover_enabled=\u00bbon|hover\u00bb background_color__hover=\u00bb#FFFFFF\u00bb background_enable_color__hover=\u00bbon\u00bb]<\/p>\n<p>9 D\u00edas y 8 noches en media pensi\u00f3n.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbTiempo de conducci\u00f3n\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf21c;||fa||900&#8243; icon_color=\u00bb#000000&#8243; image_icon_width=\u00bb50px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb animation=\u00bboff\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb background_color__hover=\u00bb#FFFFFF\u00bb background_enable_color__hover=\u00bbon\u00bb background__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<p>De 2.30 a 7.00 horas.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbNivel\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf012;||fa||900&#8243; icon_color=\u00bb#000000&#8243; image_icon_width=\u00bb50px\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb animation=\u00bboff\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb background_color__hover=\u00bb#FFFFFF\u00bb background_enable_color__hover=\u00bbon\u00bb background__hover_enabled=\u00bbon|hover\u00bb]<\/p>\n<p><a href=\"https:\/\/rutasmototours.com\/nivel-de-competencia-de-pilotaje\/\">F\u00e1cil a moderado<\/a><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_circle_counter title=\u00bbAsfalto\u00bb number=\u00bb95&#8243; bar_bg_color=\u00bb#B94E40&#8243; circle_color_alpha=\u00bb0.95&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|600|||||||\u00bb number_font=\u00bb|700|||||||\u00bb number_font_size=\u00bb40px\u00bb max_width=\u00bb200px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_circle_counter title=\u00bbRutas tur\u00edsticas\u00bb number=\u00bb85&#8243; bar_bg_color=\u00bb#B94E40&#8243; circle_color_alpha=\u00bb0.95&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|600|||||||\u00bb number_font=\u00bb|700|||||||\u00bb number_font_size=\u00bb40px\u00bb max_width=\u00bb200px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_circle_counter title=\u00bbRutas de monta\u00f1a\u00bb number=\u00bb30&#8243; bar_bg_color=\u00bb#B94E40&#8243; circle_color_alpha=\u00bb0.95&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|600|||||||\u00bb number_font=\u00bb|700|||||||\u00bb number_font_size=\u00bb40px\u00bb max_width=\u00bb200px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_circle_counter title=\u00bbRutas de autopista\u00bb number=\u00bb8&#8243; bar_bg_color=\u00bb#B94E40&#8243; circle_color_alpha=\u00bb0.95&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|600|||||||\u00bb number_font=\u00bb|700|||||||\u00bb number_font_size=\u00bb40px\u00bb max_width=\u00bb200px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_circle_counter][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||0px||false|false\u00bb custom_padding=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb26px\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||10px||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbcenter\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>La mejor temporada para viajar<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_6,1_6,1_6,1_6,1_6,1_6&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb custom_padding=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#DBA149&#8243; text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Enero<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#DBA149&#8243; text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Febrero<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#AFCCAC\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Marzo<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#AFCCAC\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Abril<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#AFCCAC\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Mayo<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#AFCCAC\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Junio<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_6,1_6,1_6,1_6,1_6,1_6&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#B94E40&#8243; text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Julio<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#B94E40&#8243; text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agosto<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#AFCCAC\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Septiembre<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#AFCCAC\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Octubre<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#AFCCAC\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Noviembre<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_6&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb background_color=\u00bb#DBA149&#8243; text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb5px|5px|5px|5px|true|true\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Diciembre<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bb#apuntarme\u00bb button_text=\u00bbApuntarme\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb|600||on|||||\u00bb custom_padding=\u00bb15px|30px|15px|30px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbMapa de la ruta\u00bb module_id=\u00bbmapa\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb da_popup_slug=\u00bbmapa\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb||10px||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbcenter\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Mapa de la ruta:<\/h2>\n<p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/07\/MAPA-MHAD9-INDA-JUIN-2026.jpg\u00bb alt=\u00bbRuta ANDPORT14&#8243; title_text=\u00bbMAPA MHAD9 INDA JUIN 2026&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection\u00bb module_id=\u00bbincluido\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#F7F7F7&#8243; da_popup_slug=\u00bbincluido\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><span>\u2705 <\/span>Que S\u00cd est\u00e1 incluido<\/h2>\n<p>F\u00f3rmula ACOMPA\u00d1ADA<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u2705 Ferry ida y vuelta a partir de Algeciras &#8211; Tanger Med.<\/p>\n<p>\u2705 Seguro sanitario, repatriaci\u00f3n y responsabilidad civil.<\/p>\n<p>\u2705 Un gu\u00eda en moto que garantice la seguridad, la asistencia y la organizaci\u00f3n del viaje.<\/p>\n<p>\u2705 Veh\u00edculo de apoyo desde Chefchaouen hasta Rabat con acompa\u00f1ante marroqu\u00ed.<\/p>\n<p>\u2705 Asistencia mec\u00e1nica express.<\/p>\n<p>\u2705 8 noches en media pensi\u00f3n y <strong>en habitaci\u00f3n individual durante todo el viaje, sin suplemento<\/strong>\u00a0en hoteles de calidad (3 a 5 estrellas seg\u00fan disponibilidad) o Kasbahs de categor\u00eda equivalentes con piscinas mayoritariamente.<\/p>\n<p>\u2705 Aparcamiento en los hoteles.<\/p>\n<p>\u2705 Tasas tur\u00edsticas en los hoteles.<\/p>\n<p>\u2705 2 noches en Merzouga con actividades (paseo en camello en el desierto y un viaje en 4&#215;4 de 2 a 3 horas en las dunas).<\/p>\n<p>\u2705 Una visita de las Minas de Ahouli (Seg\u00fan las condiciones meteorol\u00f3gicas del d\u00eda y de los d\u00edas previos).<\/p>\n<p>\u2705 Reportage foto del viaje.<\/p>\n<p>\u2705 Rutas en formato gpx.<\/p>\n<p>\u2705 Road-book del viaje.<\/p>\n<p>\u2705 Paquete regalo de bienvenida.<\/p>\n<p>\u2705 Refrescos diario.<\/p>\n<p>\u2705 Aperitivo de fin de viaje.<\/p>\n<p><span>\u26a0\ufe0f<\/span> Salida garantizada con un m\u00ednimo de 5 motos inscritas.<\/p>\n<p><span>\u26a0\ufe0f<\/span> Veh\u00edculo de asistencia garantizado con un m\u00ednimo de 7 motos inscritas.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb#apuntarme\u00bb button_text=\u00bbApuntarme\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb|600||on|||||\u00bb custom_padding=\u00bb15px|30px|15px|30px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><span>\u274c <\/span>Que NO est\u00e1 incluido<\/h2>\n<p>F\u00f3rmula ACOMPA\u00d1ADA<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u274c La motocicleta para el viaje (ver el enlace para alquilar una con nuestros socios).<\/p>\n<p>\u274c Los vuelos a\u00e9reos.<\/p>\n<p>\u274c Comida en ruta a medio d\u00eda.<\/p>\n<p>\u274c Las bebidas alcoh\u00f3licas y las bebidas no incluidas en los men\u00fas.<\/p>\n<p>\u274c Propinas.<\/p>\n<p>\u274c Peajes de autopistas (en caso de uso).<\/p>\n<p>\u274c Gasolina.<\/p>\n<p>\u274c Las multas.<\/p>\n<p>\u274c Los parkings fuera de los hoteles.<\/p>\n<p>\u274c Cualquier concepto no especificado en el apartado \u00abel viaje incluye\u00bb.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#FFFFFF\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><span>\u2705 <\/span>Que S\u00cd est\u00e1 incluido<\/h2>\n<p>F\u00f3rmula LIBERTAD<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u2705 Ferry ida y vuelta a partir de Algeciras &#8211; Tanger Med.<\/p>\n<p>\u2705 Seguro sanitario, repatriaci\u00f3n y responsabilidad civil.<\/p>\n<p>\u2705 8 noches en media pensi\u00f3n en <strong>habitaci\u00f3n individual<\/strong> <strong>durante todo el viaje, sin suplemento <\/strong>en hoteles de calidad (3 a 5 estrellas seg\u00fan disponibilidad) o Kasbahs de categor\u00eda equivalentes con piscinas mayoritariamente.<\/p>\n<p>\u2705 2 noches en Merzouga con actividades (paseo en camello en el desierto y un viaje en 4&#215;4 de 2 a 3 horas en las dunas).<\/p>\n<p>\u2705 Aparcamiento en los hoteles.<\/p>\n<p>\u2705 Tasas tur\u00edsticas en los hoteles.<\/p>\n<p>\u2705 Aparcamiento en los hoteles.<\/p>\n<p>\u2705 Rutas en formato gpx.<\/p>\n<p>\u2705 Roadbook del viaje.<\/p>\n<p>\u2705 Paquete regalo de bienvenida.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb#apuntarme\u00bb button_text=\u00bbApuntarme\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb|600||on|||||\u00bb custom_padding=\u00bb15px|30px|15px|30px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><span>\u274c <\/span>Que NO est\u00e1 incluido<\/h2>\n<p>F\u00f3rmula LIBERTAD<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u274c La motocicleta para el viaje (ver el enlace para alquilar una con nuestros socios).<\/p>\n<p>\u274c Los vuelos a\u00e9reos.<\/p>\n<p>\u274c Comida en ruta a medio d\u00eda.<\/p>\n<p>\u274c Bebidas alcoh\u00f3licas o no incluido en los men\u00fas.<\/p>\n<p>\u274c Propinas.<\/p>\n<p>\u274c Peajes de autopistas (en caso de uso).<\/p>\n<p>\u274c Gasolina.<\/p>\n<p>\u274c Las multas.<\/p>\n<p>\u274c Los parkings fuera de los hoteles.<\/p>\n<p>\u274c Cualquier concepto no espicificado en el Aprto \u00abel viaje incluye\u00bb.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbEnlaces Seguros\u00bb module_id=\u00bbenlaces\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#F7F7F7&#8243; da_popup_slug=\u00bbenlaces\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||10px||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Revisa esto atentamente<\/h2>\n<p>Por si aun no los tienes, aqu\u00ed te dejamos algunos enlaces \u00fatiles que podr\u00edas necesitar.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; use_custom_gutter=\u00bbon\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbAlquilar una moto\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf21c;||fa||900&#8243; icon_color=\u00bb#DBA149&#8243; image_icon_width=\u00bb50px\u00bb icon_alignment=\u00bbleft\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb animation=\u00bboff\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb background_color__hover=\u00bb#F7F7F7&#8243; background__hover_enabled=\u00bbon|hover\u00bb background_enable_color__hover=\u00bbon\u00bb]<\/p>\n<p><a href=\"https:\/\/www.hertzride.com\/es\/oficinas\/alquiler-de-motos-m%C3%A1laga-734\" target=\"_blank\" rel=\"noopener\">Alquilar con Hertz Ride<\/a><\/p>\n<p><a href=\"https:\/\/www.pautravelmoto.com\/\" target=\"_blank\" rel=\"noopener\">Alquilar con PauTravelMoto<\/a><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbTransporte de moto\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf474;||fa||900&#8243; icon_color=\u00bb#AFCCAC\u00bb image_icon_width=\u00bb50px\u00bb icon_alignment=\u00bbleft\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb animation=\u00bboff\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb background_color__hover=\u00bb#F7F7F7&#8243; background__hover_enabled=\u00bbon|hover\u00bb background_enable_color__hover=\u00bbon\u00bb]<\/p>\n<p><a href=\"https:\/\/www.eurotransportcar.com\/en\/motorcycle-transport\" target=\"_blank\" rel=\"noopener\">Contratar con Euro Transportcar<\/a><\/p>\n<p><a href=\"https:\/\/www.mototransport.es\/\" target=\"_blank\" rel=\"noopener\">Contratar con Moto Transport<\/a><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row column_structure=\u00bb2_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||10px||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Tabla de precios<\/h2>\n<p>Modalidad Acompa\u00f1ado y por Libre<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb18px\u00bb background_color=\u00bbrgba(202,106,75,0.5)\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d1d1d1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>ACOMPA\u00d1ADO<\/h3>\n<p>1 Piloto en habitaci\u00f3n individual<\/p>\n<p><strong><span style=\"color: #993300;\">1.790\u20ac<\/span><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb18px\u00bb background_color=\u00bbrgba(202,106,75,0.5)\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d1d1d1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Extra<\/h3>\n<p>1 Noche adicional en media pensi\u00f3n (noche previa al viaje)<\/p>\n<p><strong><span style=\"color: #993300;\">120\u20ac<\/span><\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb18px\u00bb background_color=\u00bbrgba(202,106,75,0.5)\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d1d1d1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>ACOMPA\u00d1ADO<\/h3>\n<p>1 Piloto + 1 acompa\u00f1ante en habitaci\u00f3n compartida<\/p>\n<p><strong><span style=\"color: #993300;\">2.390\u20ac<\/span><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb18px\u00bb background_color=\u00bbrgba(202,106,75,0.5)\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d1d1d1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Extra<\/h3>\n<p>1 Noche adicional en media pensi\u00f3n (noche previa al viaje)<\/p>\n<p><strong><span style=\"color: #993300;\">155\u20ac<\/span><\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb18px\u00bb background_color=\u00bbrgba(219,161,73,0.6)\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d1d1d1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>LIBERTAD<\/h3>\n<p>1 Piloto en habitaci\u00f3n individual<\/p>\n<p><strong><span style=\"color: #993300;\">1.290\u20ac<\/span><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb18px\u00bb background_color=\u00bbrgba(219,161,73,0.6)\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d1d1d1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Extra<\/h3>\n<p>1 Noche adicional en media pensi\u00f3n (noche previa al viaje)<\/p>\n<p><strong><span style=\"color: #993300;\">120\u20ac<\/span><\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb18px\u00bb background_color=\u00bbrgba(219,161,73,0.6)\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d1d1d1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>LIBERTAD<\/h3>\n<p>1 Piloto + 1 acompa\u00f1ante en habitaci\u00f3n compartida<\/p>\n<p><strong><span style=\"color: #993300;\">1.790\u20ac<\/span><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb18px\u00bb background_color=\u00bbrgba(219,161,73,0.6)\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d1d1d1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Extra<\/h3>\n<p>1 Noche adicional en media pensi\u00f3n (noche previa al viaje)<\/p>\n<p><strong><span style=\"color: #993300;\">155\u20ac<\/span><\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbCTA Ap\u00fantate\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(219,161,73,0.3)\u00bb width=\u00bb95%\u00bb max_width=\u00bb1500px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb100px||100px||true|false\u00bb da_disable_devices=\u00bboff|off|off\u00bb border_width_all=\u00bb6px\u00bb border_color_all=\u00bb#B94E40&#8243; border_style_all=\u00bbdashed\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row module_id=\u00bbapuntarme\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb95%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbcenter\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Ap\u00fantate ya a esta aventura<\/h2>\n<p>Elige tu modalidad y l\u00e1nzate a descubrir esta incre\u00edble ruta<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb3_5,2_5&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb95%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(175,204,172,0.7)\u00bb custom_padding=\u00bb15px|15px|15px|15px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb text_orientation_tablet=\u00bb\u00bb text_orientation_phone=\u00bbcenter\u00bb text_orientation_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Modalidad ACOMPA\u00d1ADO<\/h3>\n<p><strong>Haz clic en la fecha<\/strong> que desees para realizar el viaje acompa\u00f1ado.<\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_free_form=\u00bb\/* Contenedor principal *\/||.listado-productos-acompanados-and9 {||    display: flex;||    flex-direction: column;||    gap: 12px;||}||||\/* Estilo para cada l\u00ednea de producto (el enlace clicable) *\/||.producto-linea {||    display: flex;||    justify-content: space-between; \/* Distribuye los 3 elementos *\/||    align-items: center;||    text-decoration: none;||    color: #333;||    ||    \/* Fondo limpio y bordes redondeados *\/||    background-color: #f7f7f7; ||    border-radius: 10px; \/* Bordes redondeados *\/||    padding: 15px 25px;||    box-shadow: 0 1px 3px rgba(0, 0, 0, 0.05); \/* Sombra muy suave *\/||    transition: background-color 0.2s ease, box-shadow 0.2s ease;||}||||\/* Interacci\u00f3n al pasar el rat\u00f3n (Hover) *\/||.producto-linea:hover {||    background-color: #fff; \/* Se pone blanco *\/||    box-shadow: 0 4px 10px rgba(0, 0, 0, 0.1); \/* Sombra m\u00e1s pronunciada *\/||    cursor: pointer;||}||||\/* Estilos de los elementos internos *\/||.linea-titulo {||    font-weight: 700;||    flex-basis: 40%; \/* Ocupa m\u00e1s espacio *\/||    color: #333;||    padding-right: 15px;||}||||.linea-fecha {||    flex-basis: 30%; \/* Espacio para la fecha *\/||    text-align: center;||    font-size: 0.95em;||    color: #555;||    white-space: nowrap;||}||||.linea-disponibilidad {||    flex-basis: 30%; \/* Espacio para la disponibilidad *\/||    text-align: right;||    font-weight: 600;||    font-size: 0.95em;||    white-space: nowrap;||}||||\/* Colores para los \u00edconos *\/||.linea-icono-pin, .linea-icono-calendar, .linea-icono-check {||    margin-right: 8px;||    font-size: 1.1em;||}||.linea-icono-pin {||    color: #b94e40; \/* Color destacado para el pin *\/||}||||\/* Estilos de disponibilidad (como se ve en la captura: verde para disponible) *\/||.linea-disponibilidad.disponible {||    color: #28a745; \/* Verde para disponible *\/||}||||.linea-disponibilidad.agotado {||    color: #b94e40; \/* Usar el color destacado para agotado *\/||}||||\/* Responsive: Apilar en pantallas peque\u00f1as *\/||@media (max-width: 768px) {||    .producto-linea {||        flex-direction: column;||        align-items: flex-start;||        padding: 10px 15px;||    }||||    .linea-titulo, .linea-fecha, .linea-disponibilidad {||        flex-basis: 100%;||        width: 100%;||        text-align: left;||        margin-bottom: 5px;||        padding-right: 0;||    }||}||||\/* A\u00f1ade un margen inferior a cada elemento del viaje para separarlos *\/||.producto-linea {||    margin-bottom: 15px; \/* Ajusta este valor (15px) a tu gusto *\/||    border-bottom: 1px solid #eee; \/* Opcional: a\u00f1ade una l\u00ednea divisoria suave *\/||    padding-bottom: 15px; \/* Asegura que el contenido no toque la l\u00ednea divisoria *\/||}||||\/* Opcional: Eliminar el margen y la l\u00ednea divisoria del \u00faltimo elemento para que no quede espacio extra al final *\/||.producto-linea:last-child {||    margin-bottom: 0;||    border-bottom: none;||    padding-bottom: 10;||}||\u00bb global_colors_info=\u00bb{}\u00bb]<div class=\"listado-productos-ruta listado-mhad9\"><a href=\"https:\/\/rutasmototours.com\/fr\/mhad9-acompanado-del-18-al-26-de-abril-de-2026\/\" class=\"producto-linea\">    <span class=\"linea-titulo\">        <span class=\"linea-icono-pin\">\ud83d\udccd<\/span>Medio, Alto Atlas y Desierto en 9 d\u00edas    <\/span>    <span class=\"linea-fecha\">        <span class=\"linea-icono-calendar\">\ud83d\uddd3\ufe0f<\/span>18 de avril 2026    <\/span>    <span class=\"linea-disponibilidad agotado\">        <span class=\"linea-icono-check\">\u274c<\/span>Plazas agotadas    <\/span><\/a><a href=\"https:\/\/rutasmototours.com\/fr\/mhad9-acompanado-del-19-al-27-de-septiembre-de-2026\/\" class=\"producto-linea\">    <span class=\"linea-titulo\">        <span class=\"linea-icono-pin\">\ud83d\udccd<\/span>Medio, Alto Atlas y Desierto en 9 d\u00edas    <\/span>    <span class=\"linea-fecha\">        <span class=\"linea-icono-calendar\">\ud83d\uddd3\ufe0f<\/span>19 de septembre 2026    <\/span>    <span class=\"linea-disponibilidad agotado\">        <span class=\"linea-icono-check\">\u274c<\/span>Plazas agotadas    <\/span><\/a><a href=\"https:\/\/rutasmototours.com\/fr\/mhad9-acompanado-del-24-de-octubre-al-01-de-noviembre-de-2026\/\" class=\"producto-linea\">    <span class=\"linea-titulo\">        <span class=\"linea-icono-pin\">\ud83d\udccd<\/span>Medio, Alto Atlas y Desierto en 9 d\u00edas    <\/span>    <span class=\"linea-fecha\">        <span class=\"linea-icono-calendar\">\ud83d\uddd3\ufe0f<\/span>24 de octobre 2026    <\/span>    <span class=\"linea-disponibilidad disponible\">        <span class=\"linea-icono-check\">\u2705<\/span>A\u00fan quedan plazas    <\/span><\/a><\/div>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(175,204,172,0.7)\u00bb custom_padding=\u00bb15px|15px|15px|15px|true|true\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbModalidad LIBERTAD\u00bb alt=\u00bbruta en moto vuelta de andalucia en 9 dias\u00bb content_max_width=\u00bb100%\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb custom_margin=\u00bb||10px||false|false\u00bb animation=\u00bboff\u00bb text_orientation_tablet=\u00bb\u00bb text_orientation_phone=\u00bbcenter\u00bb text_orientation_last_edited=\u00bbon|phone\u00bb border_radii_image=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Escoge esta opci\u00f3n si queires realizar el viaje en la modalidad libre y a tu ritmo.<\/p>\n<p>[\/et_pb_blurb][et_pb_button button_url=\u00bbhttps:\/\/rutasmototours.com\/producto\/mhad9-marruecos-medio-alto-atlas-y-desierto-en-9-dias-libre\/\u00bb button_text=\u00bbApuntarme en Libre\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb10px\u00bb button_font=\u00bb|600||on|||||\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb15px|35px|15px|35px|true|true\u00bb custom_css_main_element=\u00bbwidth: 100%;\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbSection\u00bb module_id=\u00bbitinerario\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#F7F7F7&#8243; da_popup_slug=\u00bbitinerario\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Itinerario<\/h2>\n<p>Descripci\u00f3n de las etapas<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_3_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>D\u00eda 0<\/h3>\n<p><strong><span style=\"color: #993300;\"><em>(S\u00f3lo para los participantes que eligen una noche adicional)<\/em><\/span><\/strong><\/p>\n<ul>\n<li>Llegada en Algeciras y check in al hotel (ALBORAN o equivalente)<\/li>\n<li>Bienvenida a los participantes<\/li>\n<li>Entrega del expediente del viaje<\/li>\n<li>Reuni\u00f3n de bienvenida con explicaci\u00f3n informativa de todos los aspectos del tour<\/li>\n<li>Cena al hotel<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_3_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>D\u00eda 1 &#8211; 120 km<\/h3>\n<p><span style=\"color: #993300;\"><strong>02h30 &#8211; F\u00e1cil<\/strong><\/span><\/p>\n<ul>\n<li>Desayuno en el hotel<\/li>\n<li>Instrucciones del d\u00eda<\/li>\n<li>Punto de encuentro en el puerto de Algeciras<\/li>\n<li>Reuni\u00f3n de bienvenida con explicaci\u00f3n informativa de todos los aspectos del tour y instrucciones del dia<\/li>\n<li>Ferry Algeciras \u2013 Tanger Med<\/li>\n<li>Ruta de Tanger Med hasta Chefchaouen<\/li>\n<li>Acogida del gu\u00eda marroqu\u00ed<\/li>\n<li>Check in al hotel (PARADOR de Chefchaouen o equivalente)<\/li>\n<li>Visita libre de Chefchaouen<\/li>\n<li>Cena al hotel o fuera<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_3_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>D\u00eda 2 &#8211; 420 km<\/h3>\n<p><span style=\"color: #993300;\"><strong>07h00 &#8211; Moderado<\/strong><\/span><\/p>\n<ul>\n<li>Desayuno en el hotel<\/li>\n<li>Instrucciones del d\u00eda<\/li>\n<li>Ruta de Chefchaouen hasta Midelt<\/li>\n<li>Check in al hotel (KASBAH ASMAA o equivalente)<\/li>\n<li>Cena al hotel<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_3_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>D\u00eda 3 &#8211; 320 km<\/h3>\n<p><span style=\"color: #993300;\"><strong>06h00 &#8211; Moderado<\/strong><\/span><\/p>\n<ul>\n<li>Desayuno en el hotel<\/li>\n<li>Instrucciones del d\u00eda<\/li>\n<li>Visita de las minas de Ahouli (Seg\u00fan las condiciones meteorol\u00f3gicas del d\u00eda y de los d\u00edas previos)<\/li>\n<li>Ruta de Midelt hasta Merzouga<\/li>\n<li>Check in al hotel (MOHAYUT o equivalente)<\/li>\n<li>Cena al hotel<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_3_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>D\u00eda 4<\/h3>\n<p><span style=\"color: #993300;\"><strong>D\u00eda de descanso<\/strong><\/span><\/p>\n<ul>\n<li>Desayuno en el hotel<\/li>\n<li>Instrucciones del d\u00eda<\/li>\n<li>Almuerzo en el restaurant Nora (o equivalente)<\/li>\n<li>Paseo en camello en el desierto<\/li>\n<li>Viaje en 4 x 4 en las dunas<\/li>\n<li>Cena al hotel (MOHAYUT o equivalente)<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_3_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>D\u00eda 5 &#8211; 365 km<\/h3>\n<p><span style=\"color: #993300;\"><strong>07h00 &#8211; Moderado<\/strong><\/span><\/p>\n<ul>\n<li>Desayuno en el hotel<\/li>\n<li>Instrucciones del d\u00eda<\/li>\n<li>Ruta de Merzouga hasta las gargantas del Dad\u00e9s<\/li>\n<li>Parada en la en la c\u00e1rcel Portuguesa de Gara Medouar<\/li>\n<li>Gargantas de Todra<\/li>\n<li>Check in al hotel (Hotel New Dades o equivalente)<\/li>\n<li>Cena al hotel<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_3_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>D\u00eda 6 &#8211; 345 km<\/h3>\n<p><span style=\"color: #993300;\"><strong>06h00 &#8211; Moderado<\/strong><\/span><\/p>\n<ul>\n<li>Desayuno en el hotel<\/li>\n<li>Instrucciones del d\u00eda<\/li>\n<li>Ruta de las gargantas del Dad\u00e9s hasta Marrakech<\/li>\n<li>Gargantas de Dades<\/li>\n<li>El puerto del Tizi N\u2019Tichka<\/li>\n<li>Check in al hotel (LE JARDINS DE MARRAKECH o equivalente)<\/li>\n<li>Cena al hotel<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_3_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>D\u00eda 7 &#8211; 200 km<\/h3>\n<p><span style=\"color: #993300;\"><strong>04h00 &#8211; Moderado<\/strong><\/span><\/p>\n<ul>\n<li>Desayuno en el hotel<\/li>\n<li>Instrucciones del d\u00eda<\/li>\n<li>Ruta de Marrakech hasta Bin El Ouidane<\/li>\n<li>Las cascadas de Ouzoud<\/li>\n<li>Check in al hotel (CHEMS DU LAC o equivalente)<\/li>\n<li>Cena al hotel<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_3_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>D\u00eda 8 &#8211; 320 km<\/h3>\n<p><span style=\"color: #993300;\"><strong>06h00 &#8211; F\u00e1cil<\/strong><\/span><\/p>\n<ul>\n<li>Desayuno en el hotel<\/li>\n<li>Instrucciones del d\u00eda<\/li>\n<li>Ruta de Bien El Ouidane hasta Meknes<\/li>\n<li>Check in al hotel (TRANSATLANTIQUE o equivalente)<\/li>\n<li>Visita libre de Meknes<\/li>\n<li>Aperitivo y Cena al hotel<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb header_3_font=\u00bb|700|||||||\u00bb background_color=\u00bb#FFFFFF\u00bb custom_margin=\u00bb||10px||false|false\u00bb custom_padding=\u00bb20px|20px|20px|20px|true|true\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb border_radii=\u00bbon|5px|5px|5px|5px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>D\u00eda 9 &#8211; 300 km<\/h3>\n<p><span style=\"color: #993300;\"><strong>04h30 &#8211; F\u00e1cil<\/strong><\/span><\/p>\n<ul>\n<li>Desayuno en el hotel<\/li>\n<li>Instrucciones del d\u00eda<\/li>\n<li>Ruta de Mekn\u00e9s a T\u00e1nger Med por carretera nacional y autopista<\/li>\n<li>Ferry Tanger Med &#8211; Algeciras<\/li>\n<li>Salida de nuestro acompa\u00f1ante marroqu\u00ed<\/li>\n<li>Ha llegado el momento separarnos<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbGaler\u00eda\u00bb module_id=\u00bbgaleria\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb da_popup_slug=\u00bbgaleria\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_font_size=\u00bb40px\u00bb custom_margin=\u00bb||||false|false\u00bb header_2_font_size_tablet=\u00bb36px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Galer\u00eda<\/h2>\n<p>Fotograf\u00edas de nuestros viajes por esta ruta<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<div  id=\"jtg-1159\" class=\"modula modula-gallery modula-columns\" data-config=\"{&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;grid&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:10,&quot;mobileGutter&quot;:10,&quot;tabletGutter&quot;:10,&quot;desktopGutter&quot;:10,&quot;enableResponsive&quot;:true,&quot;tabletColumns&quot;:2,&quot;mobileColumns&quot;:1,&quot;lazyLoad&quot;:0,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:true},&quot;infinite&quot;:false},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:&quot;next&quot;,&quot;PageDown&quot;:&quot;prev&quot;,&quot;ArrowUp&quot;:&quot;prev&quot;,&quot;ArrowDown&quot;:&quot;next&quot;,&quot;ArrowRight&quot;:&quot;next&quot;,&quot;ArrowLeft&quot;:&quot;prev&quot;},&quot;wheel&quot;:&quot;slide&quot;,&quot;touch&quot;:true,&quot;backdropClick&quot;:&quot;close&quot;,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Close&quot;,&quot;NEXT&quot;:&quot;Next&quot;,&quot;PREV&quot;:&quot;Previous&quot;,&quot;Error&quot;:&quot;The requested content cannot be loaded. Please try again later.&quot;,&quot;PLAY_START&quot;:&quot;Start slideshow&quot;,&quot;PLAY_STOP&quot;:&quot;Pause slideshow&quot;,&quot;FULL_SCREEN&quot;:&quot;Full screen&quot;,&quot;THUMBS&quot;:&quot;Thumbnails&quot;,&quot;DOWNLOAD&quot;:&quot;Download&quot;,&quot;SHARE&quot;:&quot;Share&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;You can close this modal content with the ESC key&quot;,&quot;ERROR&quot;:&quot;Something Went Wrong, Please Try Again Later&quot;,&quot;IMAGE_ERROR&quot;:&quot;Image Not Found&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;HTML Element Not Found&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error Loading AJAX : Not Found&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error Loading AJAX : Forbidden&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error Loading Page&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Toggle zoom level&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Toggle thumbnails&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Toggle slideshow&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Toggle full-screen mode&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-1159&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video\\&quot; controls muted playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;}},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;\\u00a1\\u00a1Mira esta impresionante imagen!!&quot;,&quot;email_message&quot;:&quot;Este es el enlace a la imagen: %%image_link%% y este es el enlace a la galer\\u00eda: %%gallery_link%%&quot;,&quot;grid_type&quot;:&quot;automatic&quot;,&quot;rowHeight&quot;:250,&quot;lastRow&quot;:&quot;justify&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;,&quot;lightbox_devices&quot;:&quot;both&quot;}\">\n\n\t\n\t<div  class=\"modula-items grid-gallery\">\n\t\t<div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1869\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1869\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_101823-1.jpg\" title=\"IMG_20260518_101823\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_101823-1-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_101823-1-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1165\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1165\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-6\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-6-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"2076\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-2076\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518122453_0005_D_1780186193564-1.jpg\" title=\"CAM_20260518122453_0005_D_1780186193564\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518122453_0005_D_1780186193564-1-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518122453_0005_D_1780186193564-1-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1181\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1181\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-22\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-22-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1171\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1171\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-12\" crop=\"\" width=\"500\" height=\"500\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-500x500.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-500x500.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-500x500.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-1200x1200.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-150x150.jpg 150w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-768x768.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-1536x1536.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-1080x1080.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-1280x1280.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-980x980.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-480x480.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-300x300.jpg 300w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-600x600.jpg 600w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-12-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"2074\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-2074\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260517173456_0123_D_1780180186886.jpg\" title=\"CAM_20260517173456_0123_D_1780180186886\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260517173456_0123_D_1780180186886-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260517173456_0123_D_1780180186886-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1184\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1184\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-25\" crop=\"\" width=\"375\" height=\"500\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25-375x500.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25-375x500.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25.jpg 1500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25-375x500.jpg 375w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25-900x1200.jpg 900w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25-768x1024.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25-1152x1536.jpg 1152w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25-1080x1440.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25-1280x1707.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25-980x1307.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25-480x640.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-25-600x800.jpg 600w\" sizes=\"(max-width: 375px) 100vw, 375px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1161\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1161\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-2\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-2-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1180\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1180\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-21\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-21-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1167\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1167\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-8\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-8-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1178\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"Ziz Gorge.\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1178\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-19.jpg\" title=\"Ziz Gorge.\" crop=\"\" width=\"500\" height=\"333\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-19-500x333.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-19-500x333.jpg\" data-caption=\"Ziz Gorge.\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-19.jpg 612w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-19-500x333.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-19-480x320.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-19-600x400.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"jtg-description\">Ziz Gorge.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1889\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1889\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260523_201115.jpg\" title=\"IMG_20260523_201115\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260523_201115-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260523_201115-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1173\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1173\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-14\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-14-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1175\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1175\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-16\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-16-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1885\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1885\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260522_200912.jpg\" title=\"IMG_20260522_200912\" crop=\"\" width=\"500\" height=\"280\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260522_200912-500x280.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260522_200912-500x280.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1871\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1871\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_132826-1.jpg\" title=\"IMG_20260518_132826\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_132826-1-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_132826-1-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1870\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1870\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_132454.jpg\" title=\"IMG_20260518_132454\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_132454-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_132454-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1168\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1168\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-9\" crop=\"\" width=\"500\" height=\"500\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-500x500.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-500x500.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-500x500.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-1200x1200.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-150x150.jpg 150w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-768x768.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-1536x1536.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-1080x1080.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-1280x1280.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-980x980.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-480x480.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-300x300.jpg 300w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-600x600.jpg 600w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-9-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1183\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1183\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-24\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-24-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1872\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1872\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_145825.jpg\" title=\"IMG_20260518_145825\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_145825-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_145825-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1182\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1182\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-23\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-23-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1890\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1890\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260516_213011-1.jpg\" title=\"IMG_20260516_213011\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260516_213011-1-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260516_213011-1-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"2075\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-2075\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260517214936_0175_D_1780183974255-1.jpg\" title=\"CAM_20260517214936_0175_D_1780183974255\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260517214936_0175_D_1780183974255-1-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260517214936_0175_D_1780183974255-1-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1172\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1172\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-13\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-13-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1874\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1874\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_200907.jpg\" title=\"IMG_20260518_200907\" crop=\"\" width=\"500\" height=\"280\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_200907-500x280.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_200907-500x280.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1886\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1886\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260522_213247-1.jpg\" title=\"IMG_20260522_213247\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260522_213247-1-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260522_213247-1-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1166\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1166\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-7\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-7-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1884\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1884\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260522_135122-1.jpg\" title=\"IMG_20260522_135122\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260522_135122-1-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260522_135122-1-500x375.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1880\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1880\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260520_111111.jpg\" title=\"IMG_20260520_111111\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260520_111111-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260520_111111-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1176\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1176\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-17\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-17-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1877\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1877\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_134104-1.jpg\" title=\"IMG_20260519_134104\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_134104-1-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_134104-1-500x375.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1169\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1169\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-10\" crop=\"\" width=\"500\" height=\"500\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-500x500.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-500x500.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-500x500.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-1200x1200.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-150x150.jpg 150w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-768x768.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-1536x1536.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-1080x1080.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-1280x1280.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-980x980.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-480x480.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-300x300.jpg 300w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-600x600.jpg 600w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-10-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1892\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1892\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260517_200956-Copie-1.jpg\" title=\"IMG_20260517_200956 &amp;#8211; Copie\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260517_200956-Copie-1-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260517_200956-Copie-1-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1174\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1174\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-15\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-15-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1878\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1878\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_190303.jpg\" title=\"IMG_20260519_190303\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_190303-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_190303-500x375.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"2072\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-2072\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518175548_0065_D_1780189259202-1.jpg\" title=\"CAM_20260518175548_0065_D_1780189259202\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518175548_0065_D_1780189259202-1-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518175548_0065_D_1780189259202-1-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"2257\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-2257\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/07\/46651810.jpg\" title=\"46651810\" crop=\"\" width=\"500\" height=\"333\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/07\/46651810-500x333.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/07\/46651810-500x333.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1887\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1887\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260523_140516.jpg\" title=\"IMG_20260523_140516\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260523_140516-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260523_140516-500x375.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1163\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1163\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-4\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-4-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1162\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1162\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-3\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-3-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1879\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1879\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_190437-1.jpg\" title=\"IMG_20260519_190437\" crop=\"\" width=\"375\" height=\"500\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_190437-1-375x500.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_190437-1-375x500.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"2073\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-2073\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518190647_0068_D_1780189377477.jpg\" title=\"CAM_20260518190647_0068_D_1780189377477\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518190647_0068_D_1780189377477-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518190647_0068_D_1780189377477-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1876\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1876\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_074208.jpg\" title=\"IMG_20260519_074208\" crop=\"\" width=\"500\" height=\"280\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_074208-500x280.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260519_074208-500x280.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1179\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1179\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-20\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-20-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1170\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1170\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-11\" crop=\"\" width=\"500\" height=\"500\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-500x500.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-500x500.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-500x500.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-1200x1200.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-150x150.jpg 150w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-768x768.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-1536x1536.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-1080x1080.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-1280x1280.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-980x980.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-480x480.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-300x300.jpg 300w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-600x600.jpg 600w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-11-100x100.jpg 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1177\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1177\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-18\" crop=\"\" width=\"500\" height=\"375\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-500x375.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-500x375.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18.jpg 2000w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-500x375.jpg 500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-1200x900.jpg 1200w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-768x576.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-1536x1152.jpg 1536w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-510x382.jpg 510w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-1080x810.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-1280x960.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-980x735.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-480x360.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-18-600x450.jpg 600w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1875\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1875\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_205143.jpg\" title=\"IMG_20260518_205143\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_205143-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/IMG_20260518_205143-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"2077\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-2077\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518145625_0037_D_1780187814804-1.jpg\" title=\"CAM_20260518145625_0037_D_1780187814804\" crop=\"\" width=\"500\" height=\"281\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518145625_0037_D_1780187814804-1-500x281.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2026\/06\/CAM_20260518145625_0037_D_1780187814804-1-500x281.jpg\" data-caption=\"\"\/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"1164\" role=\"button\" tabindex=\"0\" rel=\"jtg-1159\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-1164\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5.jpg\" title=\"MHAD9 \u2013 Medio, Alto Atlas y Desierto-5\" crop=\"\" width=\"375\" height=\"500\" src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5-375x500.jpg\" data-src=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5-375x500.jpg\" data-caption=\"\" srcset=\"https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5.jpg 1500w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5-375x500.jpg 375w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5-900x1200.jpg 900w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5-768x1024.jpg 768w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5-1152x1536.jpg 1152w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5-1080x1440.jpg 1080w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5-1280x1707.jpg 1280w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5-980x1307.jpg 980w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5-480x640.jpg 480w, https:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/MHAD9-\u2013-Medio-Alto-Atlas-y-Desierto-5-600x800.jpg 600w\" sizes=\"(max-width: 375px) 100vw, 375px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/rutasmototours.com\/fr\/mhad9-acompanado-del-24-de-octubre-al-01-de-noviembre-de-2026\/#modula-gallery-1159\",\n\t\t\"url\"     : \"https:\/\/rutasmototours.com\/fr\/mhad9-acompanado-del-24-de-octubre-al-01-de-noviembre-de-2026\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(0,0,0,0.2)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(0,0,0,0.7) 0%|rgba(0,0,0,0.4) 20%\u00bb background_image=\u00bbhttps:\/\/rutasmototours.com\/wp-content\/uploads\/2025\/11\/pexels-sanat-anghan-25736600-10099969.webp\u00bb background_blend=\u00bboverlay\u00bb height=\u00bb90vh\u00bb da_disable_devices=\u00bboff|off|off\u00bb global_colors_info=\u00bb{}\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb positioning=\u00bbabsolute\u00bb position_origin_a=\u00bbcenter_center\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700||on|||||\u00bb text_font_size=\u00bb22px\u00bb text_line_height=\u00bb1.2em\u00bb header_font=\u00bb|800|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb50px\u00bb text_orientation=\u00bbcenter\u00bb background_layout=\u00bbdark\u00bb text_font_size_tablet=\u00bb24px\u00bb text_font_size_phone=\u00bb20px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_text_align_tablet=\u00bb\u00bb header_text_align_phone=\u00bbcenter\u00bb header_text_align_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb60px\u00bb header_font_size_phone=\u00bb38px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bb\u00bb text_orientation_phone=\u00bbcenter\u00bb [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"class_list":["post-228","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/pages\/228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/comments?post=228"}],"version-history":[{"count":11,"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/pages\/228\/revisions"}],"predecessor-version":[{"id":2686,"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/pages\/228\/revisions\/2686"}],"wp:attachment":[{"href":"https:\/\/rutasmototours.com\/fr\/wp-json\/wp\/v2\/media?parent=228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}